{"id":249,"count":40,"description":"","link":"https:\/\/blackstonegriddles.ca\/fr\/product-category\/sale\/","name":"Vente","slug":"vente","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":22,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sale Archives - Blackstone Griddles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackstonegriddles.ca\/fr\/categorie-produit\/vente\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sale Archives - Blackstone Griddles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackstonegriddles.ca\/fr\/categorie-produit\/vente\/\" \/>\n<meta property=\"og:site_name\" content=\"Blackstone Griddles\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blackstonegriddles.ca\/wp-content\/uploads\/2020\/10\/Blackstone_logo_Reverse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"433\" \/>\n\t<meta property=\"og:image:height\" content=\"91\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@weareblackstone\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/product-category\\\/sale\\\/\",\"url\":\"https:\\\/\\\/blackstonegriddles.ca\\\/product-category\\\/sale\\\/\",\"name\":\"Sale Archives - Blackstone Griddles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/product-category\\\/sale\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/product-category\\\/sale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blackstonegriddles.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/#website\",\"url\":\"https:\\\/\\\/blackstonegriddles.ca\\\/\",\"name\":\"Blackstone Griddles Canada\",\"description\":\"Blackstone Griddles official licensed dealer Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blackstonegriddles.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/#organization\",\"name\":\"Blackstone Griddles Canada\",\"url\":\"https:\\\/\\\/blackstonegriddles.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blackstonegriddles.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/blackstone-fire-logo.webp\",\"contentUrl\":\"https:\\\/\\\/blackstonegriddles.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/blackstone-fire-logo.webp\",\"width\":53,\"height\":58,\"caption\":\"Blackstone Griddles Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/blackstonegriddles.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/blackstoneproducts\\\/\",\"https:\\\/\\\/x.com\\\/weareblackstone\",\"https:\\\/\\\/www.instagram.com\\\/blackstoneproducts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCr39rimir8y3p-q1iQYidVA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des ventes - Blackstone Griddles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackstonegriddles.ca\/fr\/categorie-produit\/vente\/","og_locale":"fr_CA","og_type":"article","og_title":"Sale Archives - Blackstone Griddles","og_url":"https:\/\/blackstonegriddles.ca\/fr\/categorie-produit\/vente\/","og_site_name":"Blackstone Griddles","og_image":[{"width":433,"height":91,"url":"https:\/\/blackstonegriddles.ca\/wp-content\/uploads\/2020\/10\/Blackstone_logo_Reverse.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@weareblackstone","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blackstonegriddles.ca\/product-category\/sale\/","url":"https:\/\/blackstonegriddles.ca\/product-category\/sale\/","name":"Archives des ventes - Blackstone Griddles","isPartOf":{"@id":"https:\/\/blackstonegriddles.ca\/#website"},"breadcrumb":{"@id":"https:\/\/blackstonegriddles.ca\/product-category\/sale\/#breadcrumb"},"inLanguage":"fr-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/blackstonegriddles.ca\/product-category\/sale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blackstonegriddles.ca\/"},{"@type":"ListItem","position":2,"name":"Sale"}]},{"@type":"WebSite","@id":"https:\/\/blackstonegriddles.ca\/#website","url":"https:\/\/blackstonegriddles.ca\/","name":"Grils Blackstone Canada","description":"Blackstone Griddles distributeur officiel agr\u00e9\u00e9 Canada","publisher":{"@id":"https:\/\/blackstonegriddles.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackstonegriddles.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/blackstonegriddles.ca\/#organization","name":"Grils Blackstone Canada","url":"https:\/\/blackstonegriddles.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/blackstonegriddles.ca\/#\/schema\/logo\/image\/","url":"https:\/\/blackstonegriddles.ca\/wp-content\/uploads\/2025\/02\/blackstone-fire-logo.webp","contentUrl":"https:\/\/blackstonegriddles.ca\/wp-content\/uploads\/2025\/02\/blackstone-fire-logo.webp","width":53,"height":58,"caption":"Blackstone Griddles Canada"},"image":{"@id":"https:\/\/blackstonegriddles.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blackstoneproducts\/","https:\/\/x.com\/weareblackstone","https:\/\/www.instagram.com\/blackstoneproducts\/","https:\/\/www.youtube.com\/channel\/UCr39rimir8y3p-q1iQYidVA"]}]}},"_links":{"self":[{"href":"https:\/\/blackstonegriddles.ca\/fr\/wp-json\/wp\/v2\/product_cat\/249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackstonegriddles.ca\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/blackstonegriddles.ca\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/blackstonegriddles.ca\/fr\/wp-json\/wp\/v2\/product?product_cat=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}